{"id":15791,"date":"2025-03-21T12:33:05","date_gmt":"2025-03-21T11:33:05","guid":{"rendered":"https:\/\/www.pharmaeducationcenter.it\/?post_type=product&#038;p=15791"},"modified":"2026-07-01T11:09:33","modified_gmt":"2026-07-01T09:09:33","slug":"market-access-e-regolatorio","status":"publish","type":"product","link":"https:\/\/www.pharmaeducationcenter.it\/en\/trainings\/market-access-en\/market-access-e-regolatorio\/","title":{"rendered":"MARKET ACCESS E REGOLATORIO: sinergia, strategia, valore aggiunto"},"content":{"rendered":"<p>Dopo il successo della prima edizione, <strong>Pharma Education Center<\/strong> \u00e8 lieta di presentare la seconda edizione del corso <em>advanced<\/em> \u201c<strong>MARKET ACCESS E REGOLATORIO: sinergia, strategia, valore aggiunto<\/strong>\u201d.<\/p>\n<p>Il corso \u00e8 focalizzato sull\u2019integrazione tra <strong>Market Access<\/strong> ed <strong>Affari Regolatori<\/strong>, un tema chiave per il settore farmaceutico, con l\u2019obiettivo di comprendere le possibili sinergie e le strategie comuni di successo nei processi di accesso del farmaco.<\/p>\n<p>Il programma coprir\u00e0 le principali aree del Market Access: market access regolatorio, market access e pricing, early access, innovativit\u00e0, iter AIFA e negoziazioni, strumenti AIFA e molto altro.<br \/>\nLe due mezze giornate offriranno un\u2019importante opportunit\u00e0 di formazione e confronto con i nostri esperti, che presenteranno interessanti <u>case study ed esempi pratici<\/u>, stimolando la partecipazione attiva e lo scambio tra i partecipanti, elementi fondamentali per un efficace percorso formativo.<\/p>\n<p>Sar\u00e0 inoltre dedicato uno spazio all\u2019aggiornamento e confronto su temi internazionali di attualit\u00e0, quali il processo <strong>Joint Clinical Assessment<\/strong> (JCA) a livello EMA e le nuove dinamiche legate al <strong>Most Favoured Nation<\/strong> (MFN).<\/p>\n<p><strong>Non perdere l\u2019occasione di partecipare a questa esperienza formativa unica e coinvolgente!<\/strong><\/p>\n<p><strong>Il corso \u00e8 organizzato in collaborazione con Intexo, a ProductLife Group Company<\/strong><strong>.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo il successo della prima edizione, Pharma Education Center\u00a0\u00e8 lieta di presentare la seconda edizione del corso advanced \u201cMARKET ACCESS E REGOLATORIO: sinergia, strategia, valore aggiunto\u201d focalizzato sull\u2019integrazione\u00a0tra\u00a0Market Access\u00a0ed\u00a0Affari Regolatori, tema chiave per il mondo dell\u2019accesso del farmaco nell\u2019ottica di costruire sinergie e strategie comuni di successo nell\u2019accesso del farmaco.<\/p>\n","protected":false},"featured_media":15808,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[]},"product_brand":[],"product_cat":[164,98,117,163,106,118],"product_tag":[],"class_list":["post-15791","product","type-product","status-publish","has-post-thumbnail","product_cat-market-access-en","product_cat-affari-regolatori","product_cat-corsi-di-formazione","product_cat-market-access","product_cat-regulatory-affairs","product_cat-trainings","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-gallery-with-no-image","ast-magnify-disabled","ast-product-single-variable","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":{"corso_new_label":false,"corso_promo_label":false,"corso_pdf_programma":"","corso_programma":"<h5>Struttura del corso<\/h5>\r\n9.00 \u2013 13.00 SESSIONE GIORNO 1\r\n9.00 \u2013 13.00 SESSIONE GIORNO 2\r\n<h5>Programma<\/h5>\r\n<div class=\"et_pb_row et_pb_row_2\">\r\n<div class=\"et_pb_column et_pb_column_4_4 et_pb_column_4 et_pb_css_mix_blend_mode_passthrough et-last-child\">\r\n<div class=\"et_pb_module et_pb_tabs et_pb_tabs_0 \">\r\n<div class=\"et_pb_all_tabs\">\r\n<div class=\"et_pb_tab et_pb_tab_0 clearfix et_pb_active_content et-pb-active-slide\">\r\n<div class=\"et_pb_tab_content\">\r\n<div class=\"et_pb_section et_pb_section_4 et_section_regular\">\r\n<div class=\"et_pb_row et_pb_row_2\">\r\n<div class=\"et_pb_column et_pb_column_4_4 et_pb_column_4 et_pb_css_mix_blend_mode_passthrough et-last-child\">\r\n<div class=\"et_pb_module et_pb_tabs et_pb_tabs_0 \">\r\n<div class=\"et_pb_all_tabs\">\r\n<div class=\"et_pb_tab et_pb_tab_0 clearfix et_pb_active_content et-pb-active-slide\">\r\n<div class=\"et_pb_tab_content\">\r\n\r\n<em>(Alcuni punti del programma potranno essere soggetti a variazioni, nel rispetto degli obiettivi formativi del corso)<\/em>\r\n\r\n<strong>GIORNO 1<\/strong>\r\n\r\n<strong>Introduzione e presentazione del percorso formativo<\/strong>\r\n\r\n<strong>Giro di tavolo e presentazione dei partecipanti<\/strong>\r\n\r\n<strong>Percorso regolatorio e di accesso: dove si incontrano ed integrano<\/strong>\r\n<ul>\r\n \t<li>Tempistiche di sottomissione del dossier P&amp;R e annessi processi, nelle diverse casistiche<\/li>\r\n \t<li>Gestione strategica di aggiunta confezioni e nuove formulazioni<\/li>\r\n \t<li>Novit\u00e0 delle nuove Linee Guida AIFA dossier P&amp;R (da Aprile 2026)<\/li>\r\n \t<li>Le procedure semplificate<\/li>\r\n \t<li>Le logiche del brand versus generico\/biosimilare<\/li>\r\n \t<li>Attuale iter AIFA con CSE (Regolamento CSE Marzo 2026): cosa \u00e8 cambiato e sta cambiando<\/li>\r\n<\/ul>\r\n<strong><em>Assessment<\/em><\/strong><strong> AIFA e negoziazione<\/strong>\r\n<ul>\r\n \t<li>Criteri e logiche di negoziazione<\/li>\r\n \t<li>Scadenze contrattuali e rinegoziazione<\/li>\r\n \t<li>Gli strumenti AIFA a corollario di classe e prezzo (note, PT, registri, MEAs, ulteriori accordi finanziari, ecc.)<\/li>\r\n<\/ul>\r\n<strong>Le procedure di <em>early access<\/em><\/strong>\r\n<ul>\r\n \t<li>Overview sui programmi di <em>early access<\/em>:<\/li>\r\n<\/ul>\r\n\u2013 Legge 648\/1996\r\n\u2013 Uso compassionevole\r\n\u2013 Fondo nazionale AIFA (Legge 326\/2003 \u2013 \u201cfondo 5%\u201d)\r\n\u2013 Uso non ripetitivo di terapie avanzate\r\n<ul>\r\n \t<li>Processi di <em>early access<\/em> a confronto, riflessioni, aspetti pratici e strategici<\/li>\r\n<\/ul>\r\n<strong>Q&amp;A e chiusura 1\u00b0 giornata<\/strong>\r\n\r\n&nbsp;\r\n\r\n<strong>GIORNO 2<\/strong>\r\n\r\n<strong>La richiesta di innovativit\u00e0<\/strong>\r\n<ul>\r\n \t<li>Criteri di definizione dello status di innovativit\u00e0<\/li>\r\n \t<li>Cosa \u00e8 cambiato con la legge di Bilancio 2025<\/li>\r\n \t<li>Attuale Determina AIFA 2025 ed elementi novativi introdotti; le prime esperienze dirette<\/li>\r\n<\/ul>\r\n<strong>Distribuzione e margini <\/strong>\r\n<ul>\r\n \t<li>Matrice \u201cclassificazione\u201d versus \u201ctipologie di distribuzione\u201d<\/li>\r\n \t<li>Novit\u00e0 introdotte con la Legge di Bilancio 2025<\/li>\r\n \t<li>Focus classe A versus A-PHT<\/li>\r\n<\/ul>\r\n<strong>Aspetti di contesto nell\u2019attuale quadro internazionale<\/strong>\r\n<ul>\r\n \t<li>EMA JCA (Joint Clinical Assessment): il processo a livello EMA e coinvolgimento di AIFA pi\u00f9 a valle; il coinvolgimento delle aziende (Global\/Local); primi aspetti applicativi ed esperienze di lavoro; criticit\u00e0 ed opportunit\u00e0<\/li>\r\n \t<li>MFN (Most Favoured Nation): implicazioni, attuale impatto, visione prospettica<\/li>\r\n<\/ul>\r\n<strong>\u00a0<\/strong><strong>Q&amp;A, considerazioni finali e chiusura 2\u00b0 giornata<\/strong>\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>","corso_target":"Il corso \u00e8 rivolto a tutte le funzioni e ai ruoli, sia di sede che di territorio, che contribuiscono al business aziendale. In particolare, \u00e8 indirizzato ai professionisti delle seguenti aree: Regolatorio, Medica, Market Access (MA), Regional Access Manager (RAM), Key Account Manager (KAM), Public Affairs Manager (PAM). Inoltre, \u00e8 destinato alle Associazioni Pazienti interessate a comprendere i processi e le dinamiche del Market Access nell'introduzione di nuove terapie sul mercato, sia a livello centrale che locale. Questo \u00e8 particolarmente rilevante per i loro delegati (Patient Expert), coinvolti nelle commissioni terapeutiche nazionali, regionali e locali.","corso_competenze":[{"corso_competenze_item":"Comprendere come \u00e8 strutturato, e dove si colloca, il processo di market access rispetto a quello regolatorio;"},{"corso_competenze_item":"Comprendere e sviluppare una Pricing Strategy efficace, sia nelle fasi di predisposizione del dossier P&R, sia nel processo di negoziazione con AIFA;"},{"corso_competenze_item":"Comprendere le logiche di negoziazione del prezzo di un farmaco e conoscere i principali strumenti di governance farmaceutica di AIFA;"},{"corso_competenze_item":"Comprendere i criteri ed il processo di valutazione di un farmaco innovativo;"},{"corso_competenze_item":"Conoscere le tipologie di early access in Italia e loro applicabilit\u00e0."},{"corso_competenze_item":"Conoscere e riflettere su aspetti di contesto nell\u2019attuale quadro internazionale, quali il processo EMA JCA ed i nuovi meccanismi MFN."}]},"_links":{"self":[{"href":"https:\/\/www.pharmaeducationcenter.it\/en\/wp-json\/wp\/v2\/product\/15791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pharmaeducationcenter.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.pharmaeducationcenter.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pharmaeducationcenter.it\/en\/wp-json\/wp\/v2\/media\/15808"}],"wp:attachment":[{"href":"https:\/\/www.pharmaeducationcenter.it\/en\/wp-json\/wp\/v2\/media?parent=15791"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.pharmaeducationcenter.it\/en\/wp-json\/wp\/v2\/product_brand?post=15791"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.pharmaeducationcenter.it\/en\/wp-json\/wp\/v2\/product_cat?post=15791"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.pharmaeducationcenter.it\/en\/wp-json\/wp\/v2\/product_tag?post=15791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}